{"id":452568,"date":"2020-11-18T21:05:36","date_gmt":"2020-11-18T19:05:36","guid":{"rendered":"https:\/\/www.reead.com\/fr\/?p=452568"},"modified":"2021-06-25T19:33:13","modified_gmt":"2021-06-25T17:33:13","slug":"conseils-rencontres-pendant-confinement","status":"publish","type":"post","link":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/","title":{"rendered":"5 conseils pour faire des rencontres pendant le confinement"},"content":{"rendered":"<p>Je voudrais vous parler de ce sujet qui concerne aujourd&rsquo;hui des milliers de c\u00e9libataires. Lors du premier confinement au printemps, les inscriptions sur les sites de rencontre se sont multipli\u00e9es. Cette situation \u00e9tait id\u00e9ale pour ceux qui aiment prendre le temps de faire connaissance avec quelqu&rsquo;un (\u00e0 distance) sans la pression d&rsquo;une rencontre imminente.<\/p>\n<p>Mais voil\u00e0, une chose que personne ne pouvait pr\u00e9voir, un deuxi\u00e8me confinement est arriv\u00e9. Pour ceux qui estiment avoir assez m\u00e9dit\u00e9 sur leur vie au printemps, il est maintenant temps de vous bouger et de faire enfin, la rencontre que vous attendez.<\/p>\n<p>Parce que les rapprochements et les rencontres au temps du confinement, c&rsquo;est tout \u00e0 fait possible, je vais vous donner quelques humbles conseils pour vous aider dans cette d\u00e9marche.<\/p>\n<div id=\"attachment_452572\" style=\"width: 1210px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-452572\" class=\"wp-image-452572 size-full\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg\" alt=\"faire des rencontres pendant le confinement\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg 1200w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement-610x407.jpg 610w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement-960x640.jpg 960w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement-768x512.jpg 768w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement-272x182.jpg 272w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><p id=\"caption-attachment-452572\" class=\"wp-caption-text\">\u00a9 Can Stock Photo \/ AlexanderPokusay<\/p><\/div>\n<h2><strong>1. S&rsquo;inscrire sur un site de rencontre<\/strong><\/h2>\n<p>Pas de surprise, comme nous vivons dans un monde hyperconnect\u00e9, les sites de rencontres sont aujourd&rsquo;hui le moyen le plus simple et rapide pour faire des rencontres sans sortir de chez soi. Il en existe aujourd&rsquo;hui des dizaines et il y en a pour tous les go\u00fbts, en fonction du type de rencontre que vous souhaitez, il est important donc de s&rsquo;inscrire sur un <a href=\"https:\/\/www.capitaine-rencontre.com\/dossiers-sites-de-rencontre\/site-de-rencontre-serieux\/\" target=\"_blank\" rel=\"noopener noreferrer\">site de rencontre s\u00e9rieux<\/a><br \/>\n!<\/p>\n<p>Le principe est simple : vous cr\u00e9er votre profil, le plus attractif possible de pr\u00e9f\u00e9rence et vous s\u00e9lectionner. En fonction des crit\u00e8res de recherche que vous avez renseign\u00e9s, le site vous propose des profils divers et vari\u00e9s \u00e0 consulter. M\u00eame si vous devez attendre plusieurs semaines pour vous rencontrer, vous ne serez, pour ainsi dire, pas seul et vous vous connaitrez d\u00e9j\u00e0 un petit peu, car le confinement est propice aux longues discussions.<\/p>\n<h2><strong>2. Rendre des services autour de soi<\/strong><\/h2>\n<p>\u00catre confin\u00e9 ne signifie pas qu&rsquo;il est interdit de se rendre utile aupr\u00e8s des personnes vuln\u00e9rables et fragiles. Toujours en respectant les gestes barri\u00e8res, pourquoi ne feriez-vous pas le tour de votre voisinage afin de proposer vos services, quels qu&rsquo;ils soient.<\/p>\n<p>En plus de vous sentir utile en aidant les autres, vous risquez de faire des rencontres que vous n&rsquo;auriez jamais faites en temps normal, et qui sait, <a href=\"https:\/\/www.reead.com\/fr\/sex-friend-1722009\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>trouver un sex friend<\/strong><\/a> pour commencer?<\/p>\n<h2><strong>3. Continuer \u00e0 prendre soin de soi<\/strong><\/h2>\n<p>Ce n&rsquo;est pas parce que votre vie sociale est r\u00e9duite au minimum que vous devez vous laisser aller. \u00catre bien dans sa t\u00eate et dans son corps vous met dans de bonnes dispositions pour avoir envie de faire rencontre.<\/p>\n<p><a href=\"https:\/\/www.reead.com\/fr\/musculation\/exercices-de-musculation\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Faites de l&rsquo;exercice<\/strong><\/a>, que ce soit en ext\u00e9rieur (course \u00e0 pied par exemple) ou \u00e0 la maison. On trouve \u00e9norm\u00e9ment de vid\u00e9os en ligne qui ont pour objectif de vous aider \u00e0 vous sculpter le corps dont vous r\u00eavez. Avant de plaire aux autres, il faut se plaire \u00e0 soi-m\u00eame.<\/p>\n<p>Faites \u00e9galement attention au contenu de votre assiette. Prenez le temps de r\u00e9apprendre \u00e0 manger sainement tout en cuisinant de bons petits plats. En plus de prendre soin de votre sant\u00e9 et d&rsquo;\u00e9viter que la balance n&rsquo;affiche deux kilos de plus \u00e0 la fin du confinement, vous allez devenir un v\u00e9ritable cordon-bleu et ainsi, impressionner votre prochain rendez-vous.<\/p>\n<h2><strong>4. Sortir de chez soi pour s&rsquo;a\u00e9rer<\/strong><\/h2>\n<p>Tout en respectant les r\u00e8gles impos\u00e9es, vous \u00eates tout \u00e0 fait autoris\u00e9s \u00e0 sortir de chez vous pour prendre l&rsquo;air. On dit que les plus belles rencontres se font tout \u00e0 fait par hasard, peut-\u00eatre rencontrerez-vous votre \u00e2me s\u0153ur en promenant votre animal de compagnie ou en vous tout simplement, ou vous baladant dans un parc.<\/p>\n<p>N&rsquo;oubliez pas que, en cette p\u00e9riode, tout le monde se sent un peu seul et les personnes que vous croiserez auront plus le temps et l&rsquo;envie de discuter qu&rsquo;en temps normal.<\/p>\n<h2><strong>5. D\u00e9buter une formation en ligne<\/strong><\/h2>\n<p>Vous avez un projet depuis longtemps : changer de m\u00e9tier ou tout simplement apprendre quelque chose de nouveau. Sachez qu&rsquo;il existe une multitude de formations 100 % en ligne comme pour <a href=\"https:\/\/www.reead.com\/fr\/lancer-propre-boutique-ligne-explique-2-106642016\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>lancer sa boutique en ligne<\/strong><\/a>.<\/p>\n<p>En plus de vous stimuler et d&rsquo;acqu\u00e9rir de nouvelles comp\u00e9tences pour r\u00e9ussir \u00e0 r\u00e9aliser votre projet, vous \u00eates certain de faire des rencontres en lignes avec d&rsquo;autres personnes qui suivent la m\u00eame formation que vous. \u00c0 la fin du confinement, vous pourrez faire plus ample connaissance autour d&rsquo;un verre et parmi ces personnes, se trouvera peut-\u00eatre celle qui est faite pour vous.<\/p>\n<p>J&rsquo;esp\u00e8re que ces conseils inspireront les c\u00e9libataires. Vous n&rsquo;avez maintenant plus d&rsquo;excuses, les cartes sont entre vos mains.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;452568&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;3&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Votez pour ce post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (3 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;5 conseils pour faire des rencontres pendant le confinement&quot;,&quot;width&quot;:&quot;138&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 138px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (3 votes)    <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.<\/p>","protected":false},"author":1,"featured_media":452572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[560,559],"tags":[],"class_list":["post-452568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lifestyle","category-experiences-et-sexualite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5 conseils pour faire des rencontres pendant le confinement<\/title>\n<meta name=\"description\" content=\"Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 conseils pour faire des rencontres pendant le confinement\" \/>\n<meta property=\"og:description\" content=\"Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/\" \/>\n<meta property=\"og:site_name\" content=\"Conseils Voyage, Mode Homme et Lifestyle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welovereead\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/welovereead\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-18T19:05:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-25T17:33:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reead\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@blogdereead\" \/>\n<meta name=\"twitter:site\" content=\"@blogdereead\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/\"},\"author\":{\"name\":\"Reead\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\"},\"headline\":\"5 conseils pour faire des rencontres pendant le confinement\",\"datePublished\":\"2020-11-18T19:05:36+00:00\",\"dateModified\":\"2021-06-25T17:33:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/\"},\"wordCount\":793,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rencontres-pendant-le-confinement.jpg\",\"articleSection\":[\"Lifestyle\",\"Psycho et s\u00e9duction\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/\",\"name\":\"5 conseils pour faire des rencontres pendant le confinement\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rencontres-pendant-le-confinement.jpg\",\"datePublished\":\"2020-11-18T19:05:36+00:00\",\"dateModified\":\"2021-06-25T17:33:13+00:00\",\"description\":\"Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rencontres-pendant-le-confinement.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/rencontres-pendant-le-confinement.jpg\",\"width\":1200,\"height\":800,\"caption\":\"faire des rencontres pendant le confinement\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/conseils-rencontres-pendant-confinement-4525682020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lifestyle\",\"item\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/lifestyle\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Psycho et s\u00e9duction\",\"item\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/lifestyle\\\/experiences-et-sexualite\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"5 conseils pour faire des rencontres pendant le confinement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/\",\"name\":\"Reead.com\",\"description\":\"Conseils Voyage, Mode Homme et Lifestyle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\",\"name\":\"Reead\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\",\"width\":900,\"height\":610,\"caption\":\"Reead\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\"},\"description\":\"Reead est un blogueur voyage fran\u00e7ais bas\u00e9 \u00e0 Las Vegas et le fondateur de Reead.com, un blog lanc\u00e9 en 2009 consacr\u00e9 aux voyages, aux miles et aux programmes de fid\u00e9lit\u00e9. Sp\u00e9cialis\u00e9 dans les cartes de cr\u00e9dit voyage, les miles et points, ainsi que les programmes comme Flying Blue, American Express Membership Rewards ou les alliances a\u00e9riennes, il partage des strat\u00e9gies concr\u00e8tes pour r\u00e9duire le co\u00fbt des voyages et optimiser les r\u00e9compenses des cartes de cr\u00e9dit. Install\u00e9 aux \u00c9tats-Unis, Reead publie \u00e9galement des guides pour visiter les USA, des analyses de programmes de fid\u00e9lit\u00e9 et des retours d\u2019exp\u00e9rience sur les compagnies a\u00e9riennes, h\u00f4tels et cartes premium. Depuis plus de 15 ans, ses articles aident les voyageurs \u00e0 comprendre les miles, accumuler des points plus rapidement et voyager dans de meilleures conditions pour moins cher. Survivant du cancer, il partage aussi une vision simple : profiter de la vie et explorer le monde intelligemment.\",\"sameAs\":[\"https:\\\/\\\/www.reead.com\\\/fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/welovereead\",\"https:\\\/\\\/www.instagram.com\\\/reead\\\/?hl=fr\",\"https:\\\/\\\/www.pinterest.com\\\/reead\\\/\",\"https:\\\/\\\/x.com\\\/blogdereead\",\"https:\\\/\\\/www.youtube.com\\\/reead\"],\"gender\":\"homme\",\"knowsAbout\":[\"Voyage\",\"miles et points\"],\"knowsLanguage\":[\"Anglais\",\"Fran\u00e7ais\"],\"publishingPrinciples\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/politique-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 conseils pour faire des rencontres pendant le confinement","description":"Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/","og_locale":"fr_FR","og_type":"article","og_title":"5 conseils pour faire des rencontres pendant le confinement","og_description":"Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.","og_url":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/","og_site_name":"Conseils Voyage, Mode Homme et Lifestyle","article_publisher":"https:\/\/www.facebook.com\/welovereead","article_author":"https:\/\/www.facebook.com\/welovereead","article_published_time":"2020-11-18T19:05:36+00:00","article_modified_time":"2021-06-25T17:33:13+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg","type":"image\/jpeg"}],"author":"Reead","twitter_card":"summary_large_image","twitter_creator":"@blogdereead","twitter_site":"@blogdereead","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#article","isPartOf":{"@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/"},"author":{"name":"Reead","@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6"},"headline":"5 conseils pour faire des rencontres pendant le confinement","datePublished":"2020-11-18T19:05:36+00:00","dateModified":"2021-06-25T17:33:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/"},"wordCount":793,"commentCount":0,"publisher":{"@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6"},"image":{"@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg","articleSection":["Lifestyle","Psycho et s\u00e9duction"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/","url":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/","name":"5 conseils pour faire des rencontres pendant le confinement","isPartOf":{"@id":"https:\/\/www.reead.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#primaryimage"},"image":{"@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg","datePublished":"2020-11-18T19:05:36+00:00","dateModified":"2021-06-25T17:33:13+00:00","description":"Parce que confinement ne veut pas dire isolement social, il existe plusieurs moyens de faire des rencontres tout en respectant les r\u00e8gles.","breadcrumb":{"@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#primaryimage","url":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg","contentUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2020\/11\/rencontres-pendant-le-confinement.jpg","width":1200,"height":800,"caption":"faire des rencontres pendant le confinement"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reead.com\/fr\/conseils-rencontres-pendant-confinement-4525682020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.reead.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Lifestyle","item":"https:\/\/www.reead.com\/fr\/lifestyle\/"},{"@type":"ListItem","position":3,"name":"Psycho et s\u00e9duction","item":"https:\/\/www.reead.com\/fr\/lifestyle\/experiences-et-sexualite\/"},{"@type":"ListItem","position":4,"name":"5 conseils pour faire des rencontres pendant le confinement"}]},{"@type":"WebSite","@id":"https:\/\/www.reead.com\/fr\/#website","url":"https:\/\/www.reead.com\/fr\/","name":"Reead.com","description":"Conseils Voyage, Mode Homme et Lifestyle","publisher":{"@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reead.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6","name":"Reead","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg","url":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg","contentUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg","width":900,"height":610,"caption":"Reead"},"logo":{"@id":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg"},"description":"Reead est un blogueur voyage fran\u00e7ais bas\u00e9 \u00e0 Las Vegas et le fondateur de Reead.com, un blog lanc\u00e9 en 2009 consacr\u00e9 aux voyages, aux miles et aux programmes de fid\u00e9lit\u00e9. Sp\u00e9cialis\u00e9 dans les cartes de cr\u00e9dit voyage, les miles et points, ainsi que les programmes comme Flying Blue, American Express Membership Rewards ou les alliances a\u00e9riennes, il partage des strat\u00e9gies concr\u00e8tes pour r\u00e9duire le co\u00fbt des voyages et optimiser les r\u00e9compenses des cartes de cr\u00e9dit. Install\u00e9 aux \u00c9tats-Unis, Reead publie \u00e9galement des guides pour visiter les USA, des analyses de programmes de fid\u00e9lit\u00e9 et des retours d\u2019exp\u00e9rience sur les compagnies a\u00e9riennes, h\u00f4tels et cartes premium. Depuis plus de 15 ans, ses articles aident les voyageurs \u00e0 comprendre les miles, accumuler des points plus rapidement et voyager dans de meilleures conditions pour moins cher. Survivant du cancer, il partage aussi une vision simple : profiter de la vie et explorer le monde intelligemment.","sameAs":["https:\/\/www.reead.com\/fr\/","https:\/\/www.facebook.com\/welovereead","https:\/\/www.instagram.com\/reead\/?hl=fr","https:\/\/www.pinterest.com\/reead\/","https:\/\/x.com\/blogdereead","https:\/\/www.youtube.com\/reead"],"gender":"homme","knowsAbout":["Voyage","miles et points"],"knowsLanguage":["Anglais","Fran\u00e7ais"],"publishingPrinciples":"https:\/\/www.reead.com\/fr\/politique-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/posts\/452568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/comments?post=452568"}],"version-history":[{"count":0,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/posts\/452568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/media\/452572"}],"wp:attachment":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/media?parent=452568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/categories?post=452568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/tags?post=452568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}