{"id":309148,"date":"2019-05-05T05:55:10","date_gmt":"2019-05-05T03:55:10","guid":{"rendered":"https:\/\/www.reead.com\/fr\/?p=309148"},"modified":"2024-06-04T02:15:27","modified_gmt":"2024-06-04T00:15:27","slug":"san-francisco-city-pass","status":"publish","type":"post","link":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/","title":{"rendered":"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend"},"content":{"rendered":"<pre style=\"text-align: center;\">Cet article contient des liens affili\u00e9s et je suis susceptible de toucher une commission si vous faites un achat, merci !<\/pre>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-309190\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg\" alt=\"san francisco city pass\" width=\"900\" height=\"676\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg 900w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass-610x458.jpg 610w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass-768x577.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>La <a href=\"https:\/\/www.reead.com\/fr\/choses-absolument-faire-san-francisco-4590282022\/\" target=\"_blank\" rel=\"noopener\"><strong>premi\u00e8re fois que je me suis rendue \u00e0 San Francisco<\/strong><\/a>, c\u2019\u00e9tait en 2004 pour y passer 15 jours et rendre visite de mes amis qui y \u00e9taient en stage.<\/p>\n<p>\u00c0 cette \u00e9poque, j\u2019\u00e9tais encore \u00e9tudiant et mon budget pour les deux semaines \u00e9tait de 200 \u20ac, en gros je ne pouvais faire aucune activit\u00e9, sauf me promener et me nourrir car j\u2019avais un budget d\u2019environ 13 \u20ac par jour, soit environ 15 $. Rassurez-vous, j&rsquo;\u00e9tais le plus heureux du monde de pouvoir visiter cette ville !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-319189\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/05\/san-francisco-city-pass.jpg\" alt=\"san francisco city pass\" width=\"950\" height=\"713\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/05\/san-francisco-city-pass.jpg 950w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/05\/san-francisco-city-pass-610x458.jpg 610w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/05\/san-francisco-city-pass-768x576.jpg 768w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/p>\n<p>Heureusement aujourd\u2019hui, je suis plus \u00e9tudiant mais ce n\u2019est pas une raison pour d\u00e9penser de l\u2019argent inutilement, surtout si on part \u00e0 plusieurs !<\/p>\n<p>Je n\u2019avais jamais fait aucune des activit\u00e9s que je vais vous pr\u00e9senter ci-dessous, mais gr\u00e2ce au <strong><a class=\"wpil_keyword_link\" title=\"San Francisco\" href=\"https:\/\/www.reead.com\/fr\/voyage\/san-francisco\/\" data-wpil-keyword-link=\"linked\">San Francisco<\/a> Citypass<\/strong>, j\u2019ai r\u00e9alis\u00e9 plusieurs <strong>activit\u00e9s \u00e0 San Francisco<\/strong> lors de mon week-end en avril dernier.<\/p>\n<blockquote><p>Je vis \u00e0 <a class=\"wpil_keyword_link\" title=\"Las Vegas\" href=\"https:\/\/www.reead.com\/fr\/voyage\/las-vegas\/\" data-wpil-keyword-link=\"linked\">Las Vegas<\/a> donc voil\u00e0 pourquoi je pouvais m\u2019y rendre uniquement pour un weekend, si vous vous posez la question<\/p><\/blockquote>\n<p>La ville de San Francisco est l\u2019<strong>une des plus grandes villes am\u00e9ricaines<\/strong> et surtout une destination pr\u00e9f\u00e9r\u00e9e des Fran\u00e7ais qui se rendent aux \u00c9tats-Unis, j\u2019en ai d\u2019ailleurs beaucoup crois\u00e9 au cours de mon <strong>week-end \u00e0 San Francisc<\/strong>o.<\/p>\n<p>Je vais maintenant vous donner tous les avantages d\u2019acqu\u00e9rir un <strong>San Francisco Citypass<\/strong> et surtout vous donner mon avis sur les activit\u00e9s que j\u2019ai pu r\u00e9aliser.<\/p>\n<h2>Le San Francisco Citypass, c\u2019est quoi exactement ?<\/h2>\n<p>C\u2019est un <strong>Pass touristique<\/strong> qui vous permet d\u2019acheter de mani\u00e8re group\u00e9e plusieurs activit\u00e9s en m\u00eame temps et donc d\u2019\u00e9conomiser de l\u2019argent.<\/p>\n<p>Ce Pass est propos\u00e9 au format papier que vous pouvez recevoir par la poste, acheter en boutique ou tout simplement l&rsquo;obtenir au format num\u00e9rique en achetant ligne un billet \u00e9lectronique.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-309204\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-architecture.jpg\" alt=\"san francisco architecture\" width=\"950\" height=\"1267\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-architecture.jpg 950w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-architecture-343x458.jpg 343w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-architecture-768x1024.jpg 768w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-architecture-720x960.jpg 720w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/p>\n<h2>Quelles sont les activit\u00e9s propos\u00e9es dans le San Francisco Citypass ?<\/h2>\n<p>Ce Pass propose jusqu\u2019\u00e0 5 activit\u00e9s que vous pouvez faire \u00e0 San Francisco. En plus d\u2019\u00e9conomiser de l\u2019argent, vous gagnerez du temps car vous n\u2019aurez pas de queue \u00e0 faire pour acheter vos tickets et donc acc\u00e9der directement aux activit\u00e9s.<\/p>\n<p>Une fois la premi\u00e8re activit\u00e9 utilis\u00e9e, le Pass est valable 9 jours \u00e0 partir de cette date, ce qui vous laisse largement le temps de r\u00e9aliser toutes les activit\u00e9s incluses que je vais vous pr\u00e9senter une \u00e0 une :<\/p>\n<h3>Cable Car et Muni Bus Passeport<\/h3>\n<p>L\u2019avantage de cette premi\u00e8re activit\u00e9, c\u2019est qu\u2019elle est valable 3 jours et en illimit\u00e9 ! Vous aurez donc 3 jours de <strong>transport gratuit dans San Francisco<\/strong>.<\/p>\n<p>Vous ne pourrez pas vous d\u00e9placer dans toute la ville avec le Cable Car car les lignes sont concentr\u00e9es uniquement dans le centre-ville, mais pas de panique, vous pouvez \u00e9galement utiliser le <a href=\"https:\/\/www.sfmta.com\/getting-around\/muni\/routes-stops\" rel=\"nofollow\">r\u00e9seau Muni de la ville<\/a> pour vous rendre presque partout dans San Francisco.<\/p>\n<blockquote><p>Je vous recommande de prendre le Cable Car en d\u00e9but ou terminus, car entre les 2 stations, il est souvent plein et il est difficile de monter, surtout si vous \u00eates plusieurs<\/p><\/blockquote>\n<h3>California Academy of Sciences<\/h3>\n<p>C\u2019est l\u2019activit\u00e9 qui est la plus \u00e9loign\u00e9e de toutes les autres, et je n\u2019ai pas eu le temps de m\u2019y rendre malheureusement en 1 weekend sur place, c&rsquo;est un peu juste<\/p>\n<p>C\u2019est l\u2019un des dix <strong>plus grands mus\u00e9es d&rsquo;histoire naturelle au monde<\/strong> et il faut pr\u00e9voir selon moi une visite d\u2019au moins 2 heures.<\/p>\n<p>Manchots, for\u00eat tropicale, r\u00e9cif int\u00e9rieur de coraux, adultes et enfants en sortiront heureux ! J\u2019ai vraiment h\u00e2te d\u2019y retourner un peu plus longtemps pour visiter ce mus\u00e9e.<\/p>\n<p>Comme il se situe en dehors du centre-ville, il faut pr\u00e9voir environ 15 minutes pour s\u2019y rendre en voiture, ou environ 40 en bus avec le r\u00e9seau Muni, dont je vous parle plus haut.<\/p>\n<h3>Blue &amp; Gold Fleet Bay Cruise Adventure<\/h3>\n<p>Situ\u00e9 vers le port, embarquez pour une <strong>croisi\u00e8re d\u2019une heure sur la baie de San Francisco<\/strong> : Pont du Golden Gate, Alcatraz, Angel Island\u2026 Profitez de cette balade en bateau pour faire des photos et voir de plus pr\u00e8s les lieux touristiques les plus c\u00e9l\u00e8bres de la ville.<\/p>\n<div id=\"attachment_309193\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-309193\" class=\"wp-image-309193 size-full\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/golden-gate-san-francisco.jpg\" alt=\"Golden Gate San Francisco\" width=\"950\" height=\"713\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/golden-gate-san-francisco.jpg 950w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/golden-gate-san-francisco-610x458.jpg 610w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/golden-gate-san-francisco-768x576.jpg 768w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><p id=\"caption-attachment-309193\" class=\"wp-caption-text\">Ma photo du\u00a0Golden Gate \u00e0 San Francisco depuis le bateau<\/p><\/div>\n<h3>Aquarium of the Bay<\/h3>\n<p>Vous aimez les poissons ? Vous allez alors d\u00e9couvrir toutes les esp\u00e8ces qui vivent dans la baie de San Francisco.<\/p>\n<p>Cela a \u00e9t\u00e9 l\u2019activit\u00e9 que j\u2019ai le moins aim\u00e9e, car vous y faites vite le tour, c\u2019est tr\u00e8s petit mais cela reste tr\u00e8s amusant et instructif, on peut m\u00eame toucher des \u00e9toiles de mer. Ce que j\u2019ai pr\u00e9f\u00e9r\u00e9 c\u2019est d\u00e9couvrir les types de m\u00e9duses vivant dans la baie.<\/p>\n<div id=\"attachment_309208\" style=\"width: 960px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-309208\" class=\"wp-image-309208 size-full\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/Aquarium-of-the-Bay-san-francisco.jpg\" alt=\"Aquarium of the Bay san francisco\" width=\"950\" height=\"633\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/Aquarium-of-the-Bay-san-francisco.jpg 950w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/Aquarium-of-the-Bay-san-francisco-610x406.jpg 610w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/Aquarium-of-the-Bay-san-francisco-768x512.jpg 768w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/Aquarium-of-the-Bay-san-francisco-272x182.jpg 272w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><p id=\"caption-attachment-309208\" class=\"wp-caption-text\">2 petites m\u00e9duses que j&rsquo;ai regard\u00e9 pendant 10 minutes, elles \u00e9taient presque tout le temps ensemble !<\/p><\/div>\n<h3>Exploratorium<\/h3>\n<p>Cr\u00e9\u00e9 en 1969, l\u2019Exploratorium est un mus\u00e9e de la science et de l\u2019art, pour permettre \u00e0 toutes et \u00e0 tous d\u2019apprendre et de s\u2019\u00e9merveiller.<\/p>\n<p>Il propose des activit\u00e9s pour les petits et les grands, comme le miroir anti gravit\u00e9 pour vous donner l\u2019impression de voler. Pr\u00e9voyez 2 \u00e0 3 h sur place pour en profiter au maximum.<\/p>\n<h3>San Francisco Museum of Modern Art \u2014 SFMOMA<\/h3>\n<p>Vous avez forcement d\u00e9j\u00e0 entendu parler du <strong>MOMA<\/strong>, le plus c\u00e9l\u00e8bre \u00e9tant celui de <a class=\"wpil_keyword_link\" title=\"New York\" href=\"https:\/\/www.reead.com\/fr\/voyage\/newyork\/\" data-wpil-keyword-link=\"linked\">New York<\/a>. Si vous aimez l\u2019art contemporain, sur plusieurs niveaux vous allez adorer d\u00e9couvrir les \u0153uvres pr\u00e9sent\u00e9s \u00e0 San Francisco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-309207\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/MOMA-San-Francisco.jpg\" alt=\"MOMA San Francisco\" width=\"950\" height=\"633\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/MOMA-San-Francisco.jpg 950w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/MOMA-San-Francisco-610x406.jpg 610w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/MOMA-San-Francisco-768x512.jpg 768w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/MOMA-San-Francisco-272x182.jpg 272w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/><\/p>\n<h2>Plan de la ville avec les activit\u00e9s du San Francisco Citypass<\/h2>\n<p>Pour vous aider \u00e0 pr\u00e9parer votre planning, voici un plan avec les lieux exacts des activit\u00e9s du Pass :<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/u\/1\/embed?mid=1ZGps-p3i_gTR6H-CT9pyFtWITKYw0T5l\" width=\"100%\" height=\"480\"><\/iframe><\/p>\n<h2><strong>Quels sont les activit\u00e9s incluses ans le Citypass San Francisco<\/strong><\/h2>\n<p><strong>\u00a0<\/strong>Le Pass propose 6 activit\u00e9s mais vous permet d\u2019en effectuer 5, 4 fixes et une \u00e0 choisir :<\/p>\n<ul>\n<li>3-Day Cable Car and Muni Bus Passport<\/li>\n<li>California Academy of Sciences<\/li>\n<li>Blue &amp; Gold Fleet Bay Cruise Adventure<\/li>\n<li>Aquarium of the Bay<\/li>\n<li>Exploratorium <span style=\"color: #ff0000;\"><strong>ou<\/strong><\/span> San Francisco Museum of Modern Art \u2014 SFMOMA<\/li>\n<\/ul>\n<h2>Combien co\u00fbte le San Francisco Citypass ?<\/h2>\n<p>Il co\u00fbte moins cher que le <a href=\"https:\/\/www.reead.com\/fr\/meilleurs-pass-visiter-new-york-2433002019\/\"><strong>New York City Pass<\/strong><\/a>, ce qui est normal les activit\u00e9s ne sont pas les m\u00eames ! \u00c0 San Francisco, le <strong>Pass co\u00fbte 76$ pour les personnes de plus de 12 ans<\/strong>, et <strong>56$ pour les enfants de moins de 12 ans<\/strong>. Pour 5 activit\u00e9s, ce n\u2019est absolument pas excessif\u2026 mais est-ce vraiment rentable d\u2019acheter un <strong>San Francisco Citypass <\/strong>?<\/p>\n<p>Je vais simuler l\u2019achat individuel de toutes les activit\u00e9s du Pass pour un adulte afin de faire un comparatif clair :<\/p>\n<p><strong>Le transport<\/strong><\/p>\n<p>Comme le Pass permet des d\u00e9placements illimit\u00e9s sur les 3 premiers jours, on va simuler l\u2019achat de tickets pour 3 jours :<\/p>\n<ul>\n<li>Tickets de bus et de m\u00e9tro : 2,50$ x 3 jours x 4 trajets par jour en moyenne = 30$<\/li>\n<li>Tickets de C\u00e2ble car : 7$ x 2 trajets (histoire de le faire une fois) = 14$<\/li>\n<\/ul>\n<p>Total des frais de transport pour 3 jours = 44$<\/p>\n<p><strong>Les activit\u00e9s <\/strong><\/p>\n<ul>\n<li>California Academy of Science : 36,95$<\/li>\n<li>Blue &amp; Gold Fleet Bay Cruise Aventure : 34$<\/li>\n<li>Aquarium of the Bay : 27,95$<\/li>\n<li>Exploratorium : 29,95$<\/li>\n<li>San Francisco Museum of Modern Art : 25$<\/li>\n<\/ul>\n<p>Total si vos choisissez l\u2019activit\u00e9 Exploratorium : 172,85$<br \/>\nTotal si vos choisissez l\u2019activit\u00e9 San Francisco Museum of Modern Art : 167,90$<\/p>\n<p>Comme vous pouvez le voir dans les 2 cas vous serez largement gagnant en <strong>d\u00e9boursant 76$ au total pour un adulte !<\/strong><\/p>\n<h2><strong>O\u00f9 acheter le Citypass San Francisco ?<\/strong><\/h2>\n<p>Vous pouvez acheter votre ou vos Pass directement en ligne en cliquant sur le bouton ci-dessous, d&rsquo;ailleurs par souci de transparence je suis susceptible de toucher une commission si vous passez par mon bouton :<\/p>\n<p style=\"text-align: center;\"><a class=\"maxbutton-148 maxbutton maxbutton-achetez-votre-san-francisco-city-pass-et-faites-des-economies\" target=\"_blank\" title=\"Achetez votre San Francisco City PASS et faites des \u00e9conomies !\" rel=\"nofollow noopener sponsored\" href=\"https:\/\/www.anrdoezrs.net\/links\/8983872\/type\/dlg\/https:\/\/fr.citypass.com\/san-francisco\" data-mbga=\"{&quot;cat&quot;:&quot;CityPass&quot;,&quot;action&quot;:&quot;click&quot;,&quot;label&quot;:&quot;SanFrancisco&quot;,&quot;value&quot;:0,&quot;noninteraction&quot;:&quot;false&quot;}\"><span class='mb-text' data-nofont>Achetez votre San Francisco City PASS et faites des \u00e9conomies !<\/span><span class=\"mb-text2\"  data-nofont>Cliquez ici<\/span><\/a><\/p>\n<p>Vous pourrez choisir de le recevoir par la poste (les frais de port peuvent vous \u00eatre factur\u00e9s) ou tout simplement de recevoir un billet \u00e9lectronique \u00e0 garder dans votre t\u00e9l\u00e9phone portable.<\/p>\n<h2><strong>Comment se rendre \u00e0 San Francisco\u00a0?<\/strong><\/h2>\n<p>Pour <strong>se rendre \u00e0 San Francisco\u00a0depuis la France<\/strong>, il existe des vols directs depuis Paris sur les compagnies a\u00e9riennes <a href=\"https:\/\/www.reead.com\/fr\/air-france\/\"><strong>Air France<\/strong><\/a> et United. Pour information, San Francisco n\u2019a qu\u2019un seul a\u00e9roport international.<\/p>\n<p>\u00c9videment,\u00a0vous pouvez prendre un billet avec escale, cela pourrait vous couter beaucoup moins cher, prenez le temps de comparer les prix des billets pour San Francisco.<\/p>\n<p>Vous pouvez comparer les prix en utilisant le site <strong><a href=\"https:\/\/www.anrdoezrs.net\/links\/8983872\/type\/dlg\/https:\/\/www.expedia.fr\/Vols-Pas-Cher-San-Francisco.d178305.Voyage-Guide-Vols\" rel=\"sponsored nofollow\">Expedia<\/a><\/strong> qui propose \u00e9galement h\u00f4tel et location de voiture, si vous avez pr\u00e9vu de faire un road trip en Californie. Je suis rentr\u00e9e de San Francisco \u00e0 Vegas en voiture en faisan tune pause \u00e0 Sequoia Parc, je vous en parlerai dans un autre article.<\/p>\n<p>Avant de partir, prenez le temps de lire mes <a href=\"https:\/\/www.reead.com\/fr\/10-conseils-et-bons-plans-pour-votre-voyage-aux-usa-101342016\/\"><strong>conseils pour un voyage aux USA<\/strong><\/a>., et si vous recherchez d&rsquo;autres <strong>activit\u00e9s \u00e0 faire \u00e0 San Francisco<\/strong>, vous pouvez vous procurer un guide directement sur <a href=\"https:\/\/www.amazon.fr\/s?k=guide+voyage+san+francisco&amp;__mk_fr_FR=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=JV2A4FPTV05C&amp;sprefix=guide+voyage+san+f%2Caps%2C267&amp;ref=nb_sb_ss_i_1_18&amp;_encoding=UTF8&amp;tag=upformusicfr-21&amp;linkCode=ur2&amp;linkId=f7254e22bed8627971504118d42fcf4e&amp;camp=1642&amp;creative=6746\" target=\"_blank\" rel=\"sponsored nofollow noopener noreferrer\">Amazon<\/a>.<\/p>\n<p>Merci de votre lecture, fid\u00e9lit\u00e9\u00a0et partage de mon article avec vos amis.<\/p>\n<p style=\"text-align: center;\"><a class=\"maxbutton-148 maxbutton maxbutton-achetez-votre-san-francisco-city-pass-et-faites-des-economies\" target=\"_blank\" title=\"Achetez votre San Francisco City PASS et faites des \u00e9conomies !\" rel=\"nofollow noopener sponsored\" href=\"https:\/\/www.anrdoezrs.net\/links\/8983872\/type\/dlg\/https:\/\/fr.citypass.com\/san-francisco\" data-mbga=\"{&quot;cat&quot;:&quot;CityPass&quot;,&quot;action&quot;:&quot;click&quot;,&quot;label&quot;:&quot;SanFrancisco&quot;,&quot;value&quot;:0,&quot;noninteraction&quot;:&quot;false&quot;}\"><span class='mb-text' data-nofont>Achetez votre San Francisco City PASS et faites des \u00e9conomies !<\/span><span class=\"mb-text2\"  data-nofont>Cliquez ici<\/span><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-309200\" src=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/San-Francisco-City-Pass-2.jpg\" alt=\"San Francisco City Pass\" width=\"900\" height=\"1200\" srcset=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/San-Francisco-City-Pass-2.jpg 900w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/San-Francisco-City-Pass-2-344x458.jpg 344w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/San-Francisco-City-Pass-2-768x1024.jpg 768w,  https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/San-Francisco-City-Pass-2-720x960.jpg 720w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;309148&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;8&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;Votez pour ce post&quot;,&quot;legend&quot;:&quot;5\\\/5 - (8 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend&quot;,&quot;width&quot;:&quot;138&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 138px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            5\/5 - (8 votes)    <\/div>\n    <\/div>","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.<\/p>","protected":false},"author":1,"featured_media":309190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13272,541],"tags":[1245],"class_list":["post-309148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-san-francisco","category-voyage","tag-usa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass ! Mon test et avis<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/\" \/>\n<meta property=\"og:site_name\" content=\"Conseils Voyage, Mode Homme et Lifestyle\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/welovereead\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/welovereead\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-05T03:55:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T00:15:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reead\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@blogdereead\" \/>\n<meta name=\"twitter:site\" content=\"@blogdereead\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/\"},\"author\":{\"name\":\"Reead\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\"},\"headline\":\"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend\",\"datePublished\":\"2019-05-05T03:55:10+00:00\",\"dateModified\":\"2024-06-04T00:15:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/\"},\"wordCount\":1517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/san-francisco-city-pass.jpg\",\"keywords\":[\"Bons Plans Voyage aux USA\"],\"articleSection\":[\"San Francisco\",\"Voyage\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/\",\"name\":\"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass ! Mon test et avis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/san-francisco-city-pass.jpg\",\"datePublished\":\"2019-05-05T03:55:10+00:00\",\"dateModified\":\"2024-06-04T00:15:27+00:00\",\"description\":\"Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/san-francisco-city-pass.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/san-francisco-city-pass.jpg\",\"width\":900,\"height\":676,\"caption\":\"san francisco city pass\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/san-francisco-city-pass-3091482019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voyage\",\"item\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/voyage\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"San Francisco\",\"item\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/voyage\\\/san-francisco\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/\",\"name\":\"Reead.com\",\"description\":\"Conseils Voyage, Mode Homme et Lifestyle\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/#\\\/schema\\\/person\\\/551a8a4b469ab53c0b48bcd3846fb3c6\",\"name\":\"Reead\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\",\"url\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\",\"contentUrl\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\",\"width\":900,\"height\":610,\"caption\":\"Reead\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/reead.jpg\"},\"description\":\"Reead est un blogueur voyage fran\u00e7ais bas\u00e9 \u00e0 Las Vegas et le fondateur de Reead.com, un blog lanc\u00e9 en 2009 consacr\u00e9 aux voyages, aux miles et aux programmes de fid\u00e9lit\u00e9. Sp\u00e9cialis\u00e9 dans les cartes de cr\u00e9dit voyage, les miles et points, ainsi que les programmes comme Flying Blue, American Express Membership Rewards ou les alliances a\u00e9riennes, il partage des strat\u00e9gies concr\u00e8tes pour r\u00e9duire le co\u00fbt des voyages et optimiser les r\u00e9compenses des cartes de cr\u00e9dit. Install\u00e9 aux \u00c9tats-Unis, Reead publie \u00e9galement des guides pour visiter les USA, des analyses de programmes de fid\u00e9lit\u00e9 et des retours d\u2019exp\u00e9rience sur les compagnies a\u00e9riennes, h\u00f4tels et cartes premium. Depuis plus de 15 ans, ses articles aident les voyageurs \u00e0 comprendre les miles, accumuler des points plus rapidement et voyager dans de meilleures conditions pour moins cher. Survivant du cancer, il partage aussi une vision simple : profiter de la vie et explorer le monde intelligemment.\",\"sameAs\":[\"https:\\\/\\\/www.reead.com\\\/fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/welovereead\",\"https:\\\/\\\/www.instagram.com\\\/reead\\\/?hl=fr\",\"https:\\\/\\\/www.pinterest.com\\\/reead\\\/\",\"https:\\\/\\\/x.com\\\/blogdereead\",\"https:\\\/\\\/www.youtube.com\\\/reead\"],\"gender\":\"homme\",\"knowsAbout\":[\"Voyage\",\"miles et points\"],\"knowsLanguage\":[\"Anglais\",\"Fran\u00e7ais\"],\"publishingPrinciples\":\"https:\\\/\\\/www.reead.com\\\/fr\\\/politique-de-publication\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass ! Mon test et avis","description":"Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/","og_locale":"fr_FR","og_type":"article","og_title":"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend","og_description":"Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.","og_url":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/","og_site_name":"Conseils Voyage, Mode Homme et Lifestyle","article_publisher":"https:\/\/www.facebook.com\/welovereead","article_author":"https:\/\/www.facebook.com\/welovereead","article_published_time":"2019-05-05T03:55:10+00:00","article_modified_time":"2024-06-04T00:15:27+00:00","og_image":[{"width":900,"height":676,"url":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg","type":"image\/jpeg"}],"author":"Reead","twitter_card":"summary_large_image","twitter_creator":"@blogdereead","twitter_site":"@blogdereead","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#article","isPartOf":{"@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/"},"author":{"name":"Reead","@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6"},"headline":"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend","datePublished":"2019-05-05T03:55:10+00:00","dateModified":"2024-06-04T00:15:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/"},"wordCount":1517,"commentCount":0,"publisher":{"@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6"},"image":{"@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg","keywords":["Bons Plans Voyage aux USA"],"articleSection":["San Francisco","Voyage"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/","url":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/","name":"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass ! Mon test et avis","isPartOf":{"@id":"https:\/\/www.reead.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#primaryimage"},"image":{"@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#primaryimage"},"thumbnailUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg","datePublished":"2019-05-05T03:55:10+00:00","dateModified":"2024-06-04T00:15:27+00:00","description":"Apr\u00e8s vous avoir pr\u00e9sent\u00e9 le New York Citypass, voici le San Francisco City passe que j\u2019ai test\u00e9 lors d\u2019un week-end.","breadcrumb":{"@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#primaryimage","url":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg","contentUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2019\/04\/san-francisco-city-pass.jpg","width":900,"height":676,"caption":"san francisco city pass"},{"@type":"BreadcrumbList","@id":"https:\/\/www.reead.com\/fr\/san-francisco-city-pass-3091482019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.reead.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Voyage","item":"https:\/\/www.reead.com\/fr\/voyage\/"},{"@type":"ListItem","position":3,"name":"San Francisco","item":"https:\/\/www.reead.com\/fr\/voyage\/san-francisco\/"},{"@type":"ListItem","position":4,"name":"San Francisco Citypass : Wow g\u00e9nial d\u2019avoir eu ce Pass lors mon weekend"}]},{"@type":"WebSite","@id":"https:\/\/www.reead.com\/fr\/#website","url":"https:\/\/www.reead.com\/fr\/","name":"Reead.com","description":"Conseils Voyage, Mode Homme et Lifestyle","publisher":{"@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.reead.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.reead.com\/fr\/#\/schema\/person\/551a8a4b469ab53c0b48bcd3846fb3c6","name":"Reead","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg","url":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg","contentUrl":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg","width":900,"height":610,"caption":"Reead"},"logo":{"@id":"https:\/\/www.reead.com\/fr\/wp-content\/uploads\/2018\/12\/reead.jpg"},"description":"Reead est un blogueur voyage fran\u00e7ais bas\u00e9 \u00e0 Las Vegas et le fondateur de Reead.com, un blog lanc\u00e9 en 2009 consacr\u00e9 aux voyages, aux miles et aux programmes de fid\u00e9lit\u00e9. Sp\u00e9cialis\u00e9 dans les cartes de cr\u00e9dit voyage, les miles et points, ainsi que les programmes comme Flying Blue, American Express Membership Rewards ou les alliances a\u00e9riennes, il partage des strat\u00e9gies concr\u00e8tes pour r\u00e9duire le co\u00fbt des voyages et optimiser les r\u00e9compenses des cartes de cr\u00e9dit. Install\u00e9 aux \u00c9tats-Unis, Reead publie \u00e9galement des guides pour visiter les USA, des analyses de programmes de fid\u00e9lit\u00e9 et des retours d\u2019exp\u00e9rience sur les compagnies a\u00e9riennes, h\u00f4tels et cartes premium. Depuis plus de 15 ans, ses articles aident les voyageurs \u00e0 comprendre les miles, accumuler des points plus rapidement et voyager dans de meilleures conditions pour moins cher. Survivant du cancer, il partage aussi une vision simple : profiter de la vie et explorer le monde intelligemment.","sameAs":["https:\/\/www.reead.com\/fr\/","https:\/\/www.facebook.com\/welovereead","https:\/\/www.instagram.com\/reead\/?hl=fr","https:\/\/www.pinterest.com\/reead\/","https:\/\/x.com\/blogdereead","https:\/\/www.youtube.com\/reead"],"gender":"homme","knowsAbout":["Voyage","miles et points"],"knowsLanguage":["Anglais","Fran\u00e7ais"],"publishingPrinciples":"https:\/\/www.reead.com\/fr\/politique-de-publication\/"}]}},"_links":{"self":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/posts\/309148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/comments?post=309148"}],"version-history":[{"count":0,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/posts\/309148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/media\/309190"}],"wp:attachment":[{"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/media?parent=309148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/categories?post=309148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.reead.com\/fr\/wp-json\/wp\/v2\/tags?post=309148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}